{"id":192,"date":"2021-08-11T09:10:14","date_gmt":"2021-08-11T07:10:14","guid":{"rendered":"https:\/\/www.thermohauser.de\/blog\/?p=192"},"modified":"2021-08-12T11:16:12","modified_gmt":"2021-08-12T09:16:12","slug":"um-den-globus-das-sind-die-lieblings-office-lunches","status":"publish","type":"post","link":"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/","title":{"rendered":"Um den Globus: Das sind die Lieblings-Office-Lunches"},"content":{"rendered":"<div class=\"lazyblock-teaserabsatz-Z1xisIR align wp-block-lazyblock-teaserabsatz\"><p class=\"teaserabsatz\"><p>Ob das Baguette, ein K\u00e4se-Sandwich, Pasta oder andere Leckereien: Ein Streifzug durch die Lieblings-Office-Lunches der Welt macht deutlich, wie einfach und lecker internationale Food-Klassiker sind. Hier geht\u2019s zur \u00dcbersicht.<\/p>\n<p>Geschmack ist kulturell gepr\u00e4gt. Die verschiedenen L\u00e4nderk\u00fcchen der Welt haben sehr spezifische Lieblingsgerichte hervorgebracht. Ein Streifzug durch die Top-Office-Lunches der Welt belegt dies eindrucksvoll und wir stellen Ihnen beliebte Gerichte vor.<\/p><\/p><\/div>\n\n\n<p class=\"wp-block-paragraph\">Fr\u00fcher waren die kulinarischen Vorlieben vor allem vom Nahrungsangebot der Umgebung gepr\u00e4gt. Das Angebot der Natur ist der Ausgangspunkt f\u00fcr die verschiedenen L\u00e4nderk\u00fcchen und ihre typischen Spezialit\u00e4ten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der globalen Welt verschwimmen die Vorlieben ein wenig. Aber nur ein bisschen. Denn ein anderer Aspekt tr\u00e4gt wesentlich dazu bei, dass die l\u00e4nderspezifischen Vorlieben erhalten bleiben: Es ist die kulturelle Pr\u00e4gung.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die Sehnsucht nach geschmacklicher Herausforderung<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Im Prinzip ist Geschmack reine Lernsache. Kleinkinder entwickeln ihre Geschmacksf\u00e4higkeit nach dem reinen \u201eMere-Exposure-Effekt\u201c. Dies bedeutet: Je h\u00e4ufiger ihnen ein gewisser Geschmack dargeboten wird, desto besser schmeckt er ihnen. Anders ausgedr\u00fcckt: Menschen lassen sich gewisse Gerichte schmackhaft machen. Der Gegenspieler dieses Effektes ist die \u201espezifisch-sensorische S\u00e4ttigung\u201c. Selbst am besten M\u00f6hrenbrei kann man sich \u00fcberessen. Schon Kinder wollen st\u00e4ndig neue geschmackliche Herausforderungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unser K\u00f6rper wei\u00df, was er will und braucht. Er ben\u00f6tigt eine ganze Palette verschiedener N\u00e4hrstoffe. Der Appetit hat einen guten Grund. Vor diesem Hintergrund entwickeln sich die K\u00fcchen verschiedener L\u00e4nder \u2013 Abwechslung ist wichtig. Aber es gibt in jedem Land bestimmte Klassiker, die einfach auf die Speisekarte geh\u00f6ren. Die kulturelle Pr\u00e4gung bleibt vielen Menschen ein Leben lang erhalten. Die Top-Ten der beliebtesten Office-Lunches aus den L\u00e4ndern der Welt ergibt ein buntes Mosaik an verschiedenen Geschmacksrichtungen \u2013 und an manchen Stellen best\u00e4tigt es vorhandene Klischees.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">England und seine Vorliebe f\u00fcr Suppen und Sandwiches<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Leicht und locker m\u00f6gen es die Briten am Mittag. Besonders beliebt sind Gem\u00fcsesuppen wie Kartoffel-Lauch-Suppe. Bei den Sandwiches stehen Thunfisch-H\u00e4ppchen oben auf der Liste. Daneben werden sogenannte Malteser (Malzb\u00e4llchen) gerne genascht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wer sich von den Briten inspirieren l\u00e4sst, kann mit den leichten Mahlzeiten den kleinen Hunger schnell stillen und spart bei der Zubereitung eine Menge Zeit, da Suppen und Sandwiches im Nu zubereitet sind.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pizza \u00e0 la USA<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Keine Regel ohne Ausnahme. Top of the Pops in den USA ist ein Gericht, das urspr\u00fcnglich aus einer anderen L\u00e4nderk\u00fcche stammt: Pizza. \u00dcberraschenderweise ist die sogenannte \u201ePizza Peperoni\u201c besonders beliebt und immer ganz vorne mit dabei. Dazu wird gerne Cola gereicht. F\u00fcr diejenigen, die auf ein Dessert danach nicht verzichten m\u00f6chten, wird die Mahlzeit oftmals mit einem leckeren Schokoeis abgerundet.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Frankreich und das Baguette \u2013 nur ein Klischee?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr eine echte franz\u00f6sische Mahlzeit reicht leider die Zeit nicht. Unter vier G\u00e4ngen und drei Stunden kommt man dabei nicht weg. Darum greift man in Frankreich als Business-Lunch gerne zum \u00fcppig belegten Schinken-Butter-Baguette. Das hat vor allem den Vorteil, dass es im Handumdrehen zubereitet ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als s\u00fc\u00dfen Abschluss wird gerne zu einem St\u00fcck des Dessert-Klassikers \u201eTarte Tatin\u201c gegriffen. Hierbei handelt es sich um einen ber\u00fchmten Apfelkuchen, der verkehrt herum gebacken wird.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wie sehen die Lieblings-Office-Lunches in weiteren L\u00e4ndern aus?<\/h2>\n\n\n\n<div class=\"wp-block-block-accordion eb-accordion-container\" style=\"background-image:none;margin:auto;padding:0px 0px 0px 0px;border:0px solid #000000;border-radius:0px;box-shadow:0px 0px 0px 0px #dedede\" data-id=\"ed16f\" data-accordion-type=\"toggle\" data-transition-function=\"ease\" data-tab-icon=\"fas fa-angle-right\" data-expanded-icon=\"fas fa-angle-down\" data-active-color=\"#4a5059\" data-title-color=\"#4a5059\" data-active-title-color=\"#ffffff\" data-icon-color=\"#4a5059\" data-original-color=\"#ededed\" data-background-image-url=\"\"><div class=\"eb-accordion-wrapper \"><div class=\"eb-accordion-title-wrapper\" style=\"flex-direction:row-reverse;justify-content:space-between;border-width:0px;background-color:#edf1f7;border-color:transparent;background-image:transparent;border-radius:0px;border-style:solid;border-image:none;box-shadow:0px 0px 0px 0px #dbdbdb;margin:10px 0px 0px 0px;padding:0px 0px 0px 0px\"><span class=\"eb-accordion-icon-wrapper\" style=\"display:flex;margin:0px 0px 0px 0px;background-image:false;border-radius:0%;box-shadow:0px 0px 0px 0px #000000\"><span class=\"fas fa-angle-right eb-accordion-icon\" style=\"color:#4a5059;font-size:14px;padding:0px 0px 0px 0px ;display:flex;flex-direction:column;justify-content:center\"><\/span><\/span><h5 class=\"eb-accordion-title\" style=\"color:#4a5059;font-size:16px;font-weight:normal;margin:0\">Italien<\/h5><\/div><div class=\"eb-accordion-content-wrapper\" style=\"text-align:left;background-color:transparent;background-image:none;border-style:solid;border-width:1px 1px 1px 1px;border-color:undefined;box-shadow:0px 0px 0px  0px undefined;transition-duration:500ms;transition-property:height,overflow,opacity;max-height:2000px;overflow:hidden\"><p class=\"eb-accordion-content\" style=\"margin:10px 10px 10px 10px;padding:0px 0px 0px 0px;font-size:18px;font-weight:normal;color:#4a5059;transition:all 500ms\">Kohlenhydrate und frische Zutaten geh\u00f6ren zum typischen italienischen Mittagessen. Pasta steht ganz oben. Gerne mit Thunfisch, Oliven und Tomaten. Eine Schale mit frischem Salat geh\u00f6rt dazu und Brot muss auf dem Tisch sein. Der Espresso danach darf nicht fehlen.<\/p><\/div><\/div><div class=\"eb-accordion-wrapper \"><div class=\"eb-accordion-title-wrapper\" style=\"flex-direction:row-reverse;justify-content:space-between;border-width:0px;background-color:#edf1f7;border-color:transparent;background-image:transparent;border-radius:0px;border-style:solid;border-image:none;box-shadow:0px 0px 0px 0px #dbdbdb;margin:10px 0px 0px 0px;padding:0px 0px 0px 0px\"><span class=\"eb-accordion-icon-wrapper\" style=\"display:flex;margin:0px 0px 0px 0px;background-image:false;border-radius:0%;box-shadow:0px 0px 0px 0px #000000\"><span class=\"fas fa-angle-right eb-accordion-icon\" style=\"color:#4a5059;font-size:14px;padding:0px 0px 0px 0px ;display:flex;flex-direction:column;justify-content:center\"><\/span><\/span><h5 class=\"eb-accordion-title\" style=\"color:#4a5059;font-size:16px;font-weight:normal;margin:0\">Niederlande<\/h5><\/div><div class=\"eb-accordion-content-wrapper\" style=\"text-align:left;background-color:transparent;background-image:none;border-style:solid;border-width:1px 1px 1px 1px;border-color:undefined;box-shadow:0px 0px 0px  0px undefined;transition-duration:500ms;transition-property:height,overflow,opacity;max-height:2000px;overflow:hidden\"><p class=\"eb-accordion-content\" style=\"margin:10px 10px 10px 10px;padding:0px 0px 0px 0px;font-size:18px;font-weight:normal;color:#4a5059;transition:all 500ms\">Die Broodjes-Kultur ist kein Zufall. An jeder Stra\u00dfenecke werden die beliebten und fantasievoll belegten Brotstangen angeboten. Auch in den B\u00fcros rangieren die simplen, aber guten Broodjes ganz oben auf der Beliebtheitsskala. Nat\u00fcrlich gerne mit Gouda.<\/p><\/div><\/div><div class=\"eb-accordion-wrapper \"><div class=\"eb-accordion-title-wrapper\" style=\"flex-direction:row-reverse;justify-content:space-between;border-width:0px;background-color:#edf1f7;border-color:transparent;background-image:transparent;border-radius:0px;border-style:solid;border-image:none;box-shadow:0px 0px 0px 0px #dbdbdb;margin:10px 0px 0px 0px;padding:0px 0px 0px 0px\"><span class=\"eb-accordion-icon-wrapper\" style=\"display:flex;margin:0px 0px 0px 0px;background-image:false;border-radius:0%;box-shadow:0px 0px 0px 0px #000000\"><span class=\"fas fa-angle-right eb-accordion-icon\" style=\"color:#4a5059;font-size:14px;padding:0px 0px 0px 0px ;display:flex;flex-direction:column;justify-content:center\"><\/span><\/span><h5 class=\"eb-accordion-title\" style=\"color:#4a5059;font-size:16px;font-weight:normal;margin:0\">Indien<\/h5><\/div><div class=\"eb-accordion-content-wrapper\" style=\"text-align:left;background-color:transparent;background-image:none;border-style:solid;border-width:1px 1px 1px 1px;border-color:undefined;box-shadow:0px 0px 0px  0px undefined;transition-duration:500ms;transition-property:height,overflow,opacity;max-height:2000px;overflow:hidden\"><p class=\"eb-accordion-content\" style=\"margin:10px 10px 10px 10px;padding:0px 0px 0px 0px;font-size:18px;font-weight:normal;color:#4a5059;transition:all 500ms\">Reis und Mungobohnen stehen ganz oben auf der Liste der indischen B\u00fcro-Klassiker. Gerne wird dazu auch ein Erbsen-Kartoffel-Curry verzehrt. Als Getr\u00e4nk bevorzugen die meisten einen Chai-Tee. Hierbei handelt es sich um ein ayuverdisches Trend-Getr\u00e4nk aus schwarzem Tee und Gew\u00fcrzen wie Kardamon, Fencel und Anis.<\/p><\/div><\/div><div class=\"eb-accordion-wrapper \"><div class=\"eb-accordion-title-wrapper\" style=\"flex-direction:row-reverse;justify-content:space-between;border-width:0px;background-color:#edf1f7;border-color:transparent;background-image:transparent;border-radius:0px;border-style:solid;border-image:none;box-shadow:0px 0px 0px 0px #dbdbdb;margin:10px 0px 0px 0px;padding:0px 0px 0px 0px\"><span class=\"eb-accordion-icon-wrapper\" style=\"display:flex;margin:0px 0px 0px 0px;background-image:false;border-radius:0%;box-shadow:0px 0px 0px 0px #000000\"><span class=\"fas fa-angle-right eb-accordion-icon\" style=\"color:#4a5059;font-size:14px;padding:0px 0px 0px 0px ;display:flex;flex-direction:column;justify-content:center\"><\/span><\/span><h5 class=\"eb-accordion-title\" style=\"color:#4a5059;font-size:16px;font-weight:normal;margin:0\">Brasilien<\/h5><\/div><div class=\"eb-accordion-content-wrapper\" style=\"text-align:left;background-color:transparent;background-image:none;border-style:solid;border-width:1px 1px 1px 1px;border-color:undefined;box-shadow:0px 0px 0px  0px undefined;transition-duration:500ms;transition-property:height,overflow,opacity;max-height:2000px;overflow:hidden\"><p class=\"eb-accordion-content\" style=\"margin:10px 10px 10px 10px;padding:0px 0px 0px 0px;font-size:18px;font-weight:normal;color:#4a5059;transition:all 500ms\">Mit Feijoada meint man in Brasilien bunte Eint\u00f6pfe mit heimischem Gem\u00fcse, aber auch Fleisch darf dabei sein. Meistens bestimmen Rind- und Schweinefleisch den Geschmack des Gerichts. Dazu wird Reis gereicht. Kokoswasser ist das Getr\u00e4nk der ersten Wahl.<\/p><\/div><\/div><div class=\"eb-accordion-wrapper \"><div class=\"eb-accordion-title-wrapper\" style=\"flex-direction:row-reverse;justify-content:space-between;border-width:0px;background-color:#edf1f7;border-color:transparent;background-image:transparent;border-radius:0px;border-style:solid;border-image:none;box-shadow:0px 0px 0px 0px #dbdbdb;margin:10px 0px 0px 0px;padding:0px 0px 0px 0px\"><span class=\"eb-accordion-icon-wrapper\" style=\"display:flex;margin:0px 0px 0px 0px;background-image:false;border-radius:0%;box-shadow:0px 0px 0px 0px #000000\"><span class=\"fas fa-angle-right eb-accordion-icon\" style=\"color:#4a5059;font-size:14px;padding:0px 0px 0px 0px ;display:flex;flex-direction:column;justify-content:center\"><\/span><\/span><h5 class=\"eb-accordion-title\" style=\"color:#4a5059;font-size:16px;font-weight:normal;margin:0\">T\u00fcrkei<\/h5><\/div><div class=\"eb-accordion-content-wrapper\" style=\"text-align:left;background-color:transparent;background-image:none;border-style:solid;border-width:1px 1px 1px 1px;border-color:undefined;box-shadow:0px 0px 0px  0px undefined;transition-duration:500ms;transition-property:height,overflow,opacity;max-height:2000px;overflow:hidden\"><p class=\"eb-accordion-content\" style=\"margin:10px 10px 10px 10px;padding:0px 0px 0px 0px;font-size:18px;font-weight:normal;color:#4a5059;transition:all 500ms\">Warmes Fladenbrot, lecker! Zu Pide greift man in der T\u00fcrkei gerne. Das ist unkompliziert, knusprig und schmeckt gut. H\u00e4ufig bleibt man fleischlos. Spinat und Feta sind dabei die Nummer eins.<\/p><\/div><\/div><div class=\"eb-accordion-wrapper \"><div class=\"eb-accordion-title-wrapper\" style=\"flex-direction:row-reverse;justify-content:space-between;border-width:0px;background-color:#edf1f7;border-color:transparent;background-image:transparent;border-radius:0px;border-style:solid;border-image:none;box-shadow:0px 0px 0px 0px #dbdbdb;margin:10px 0px 0px 0px;padding:0px 0px 0px 0px\"><span class=\"eb-accordion-icon-wrapper\" style=\"display:flex;margin:0px 0px 0px 0px;background-image:false;border-radius:0%;box-shadow:0px 0px 0px 0px #000000\"><span class=\"fas fa-angle-right eb-accordion-icon\" style=\"color:#4a5059;font-size:14px;padding:0px 0px 0px 0px ;display:flex;flex-direction:column;justify-content:center\"><\/span><\/span><h5 class=\"eb-accordion-title\" style=\"color:#4a5059;font-size:16px;font-weight:normal;margin:0\">\u00d6sterreich<\/h5><\/div><div class=\"eb-accordion-content-wrapper\" style=\"text-align:left;background-color:transparent;background-image:none;border-style:solid;border-width:1px 1px 1px 1px;border-color:undefined;box-shadow:0px 0px 0px  0px undefined;transition-duration:500ms;transition-property:height,overflow,opacity;max-height:2000px;overflow:hidden\"><p class=\"eb-accordion-content\" style=\"margin:10px 10px 10px 10px;padding:0px 0px 0px 0px;font-size:18px;font-weight:normal;color:#4a5059;transition:all 500ms\">In der Alpenrepublik steht das panierte Schnitzel ganz oben auf der Hitliste. Wer h\u00e4tte das gedacht? Dazu w\u00e4hlt man in \u00d6sterreich gerne Kr\u00e4uterkartoffeln und einen gemischten Salat. Als Getr\u00e4nk reicht ein frisches Mineralwasser.<\/p><\/div><\/div><div class=\"eb-accordion-wrapper \"><div class=\"eb-accordion-title-wrapper\" style=\"flex-direction:row-reverse;justify-content:space-between;border-width:0px;background-color:#edf1f7;border-color:transparent;background-image:transparent;border-radius:0px;border-style:solid;border-image:none;box-shadow:0px 0px 0px 0px #dbdbdb;margin:10px 0px 0px 0px;padding:0px 0px 0px 0px\"><span class=\"eb-accordion-icon-wrapper\" style=\"display:flex;margin:0px 0px 0px 0px;background-image:false;border-radius:0%;box-shadow:0px 0px 0px 0px #000000\"><span class=\"fas fa-angle-right eb-accordion-icon\" style=\"color:#4a5059;font-size:14px;padding:0px 0px 0px 0px ;display:flex;flex-direction:column;justify-content:center\"><\/span><\/span><h5 class=\"eb-accordion-title\" style=\"color:#4a5059;font-size:16px;font-weight:normal;margin:0\">Deutschland<\/h5><\/div><div class=\"eb-accordion-content-wrapper\" style=\"text-align:left;background-color:transparent;background-image:none;border-style:solid;border-width:1px 1px 1px 1px;border-color:undefined;box-shadow:0px 0px 0px  0px undefined;transition-duration:500ms;transition-property:height,overflow,opacity;max-height:2000px;overflow:hidden\"><p class=\"eb-accordion-content\" style=\"margin:10px 10px 10px 10px;padding:0px 0px 0px 0px;font-size:18px;font-weight:normal;color:#4a5059;transition:all 500ms\">Evergreen: Currywurst-Pommes, bitte! Die sichere Nummer unter den Kantinengerichten. Gesund wird es hinterher, wenn sich die G\u00e4ste einen Apfel schnappen. Mineralwasser und Kaffee sind dazu die Top-Beverages.<\/p><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Die verschiedenen Lieblings-Office-Lunches aus anderen L\u00e4ndern stellen f\u00fcr viele Gastronomen eine gute Inspiration dar. Durch die vielf\u00e4ltige Auswahl kulinarischer Leckereien, kann das hauseigene Speisen-Angebot erweitert werden, sodass auch die Kundschaft sich an der internationalen Auswahl freuen kann.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fr\u00fcher waren die kulinarischen Vorlieben vor allem vom Nahrungsangebot der Umgebung gepr\u00e4gt. Das Angebot der Natur ist der Ausgangspunkt f\u00fcr die verschiedenen L\u00e4nderk\u00fcchen und ihre typischen Spezialit\u00e4ten. In der globalen Welt verschwimmen die Vorlieben ein wenig. Aber nur ein bisschen. Denn ein anderer Aspekt tr\u00e4gt wesentlich dazu bei, dass die l\u00e4nderspezifischen Vorlieben erhalten bleiben: Es&hellip; <a class=\"more-link\" href=\"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/\"><span class=\"screen-reader-text\">Um den Globus: Das sind die Lieblings-Office-Lunches<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Um den Globus: Das sind die Lieblings-Office-Lunches &#187; Thermohauser Blog<\/title>\n<meta name=\"description\" content=\"Italien, Frankreich, Indien und Co.: Diese Lieblings-Office-Lunches sorgen f\u00fcr ein kleines bisschen Urlaubs-Flair im Office! Lassen Sie sich von diesen Leckereien \u00fcberzeugen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Um den Globus: Das sind die Lieblings-Office-Lunches &#187; Thermohauser Blog\" \/>\n<meta property=\"og:description\" content=\"Italien, Frankreich, Indien und Co.: Diese Lieblings-Office-Lunches sorgen f\u00fcr ein kleines bisschen Urlaubs-Flair im Office! Lassen Sie sich von diesen Leckereien \u00fcberzeugen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/\" \/>\n<meta property=\"og:site_name\" content=\"Thermohauser Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-11T07:10:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-12T09:16:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thermohauser.de\/blog\/wp-content\/uploads\/2021\/08\/202106_Blogartikel-05_iStock-1132762174_klein.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1241\" \/>\n\t<meta property=\"og:image:height\" content=\"827\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LOE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"LOE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/um-den-globus-das-sind-die-lieblings-office-lunches\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/um-den-globus-das-sind-die-lieblings-office-lunches\\\/\"},\"author\":{\"name\":\"LOE\",\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/#\\\/schema\\\/person\\\/07f21edce43c3991b015962b083eb122\"},\"headline\":\"Um den Globus: Das sind die Lieblings-Office-Lunches\",\"datePublished\":\"2021-08-11T07:10:14+00:00\",\"dateModified\":\"2021-08-12T09:16:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/um-den-globus-das-sind-die-lieblings-office-lunches\\\/\"},\"wordCount\":790,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/um-den-globus-das-sind-die-lieblings-office-lunches\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/202106_Blogartikel-05_iStock-1132762174_klein.jpg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/um-den-globus-das-sind-die-lieblings-office-lunches\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/um-den-globus-das-sind-die-lieblings-office-lunches\\\/\",\"url\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/um-den-globus-das-sind-die-lieblings-office-lunches\\\/\",\"name\":\"Um den Globus: Das sind die Lieblings-Office-Lunches &#187; Thermohauser Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/um-den-globus-das-sind-die-lieblings-office-lunches\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/um-den-globus-das-sind-die-lieblings-office-lunches\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/202106_Blogartikel-05_iStock-1132762174_klein.jpg\",\"datePublished\":\"2021-08-11T07:10:14+00:00\",\"dateModified\":\"2021-08-12T09:16:12+00:00\",\"description\":\"Italien, Frankreich, Indien und Co.: Diese Lieblings-Office-Lunches sorgen f\u00fcr ein kleines bisschen Urlaubs-Flair im Office! Lassen Sie sich von diesen Leckereien \u00fcberzeugen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/um-den-globus-das-sind-die-lieblings-office-lunches\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/um-den-globus-das-sind-die-lieblings-office-lunches\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/um-den-globus-das-sind-die-lieblings-office-lunches\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/202106_Blogartikel-05_iStock-1132762174_klein.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/202106_Blogartikel-05_iStock-1132762174_klein.jpg\",\"width\":1241,\"height\":827,\"caption\":\"Weltweit gibt es verschiedene Lieblings-Office-Lunches. F\u00fcr ein bisschen Abwechslung sorgt eine \u00dcbersicht einiger B\u00fcro-Klassiker. Wie w\u00e4re es mal mit Pasta mit Thunfisch, Oliven und Tomaten?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/um-den-globus-das-sind-die-lieblings-office-lunches\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Allgemein\",\"item\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/allgemein\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Um den Globus: Das sind die Lieblings-Office-Lunches\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/\",\"name\":\"Thermohauser Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/#organization\",\"name\":\"thermohauser GmbH\",\"url\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.thermohauser.de\\\/ratgeber\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/logo-tablet.png\",\"contentUrl\":\"https:\\\/\\\/www.thermohauser.de\\\/ratgeber\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/logo-tablet.png\",\"width\":175,\"height\":80,\"caption\":\"thermohauser GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.thermohauser.de\\\/blog\\\/#\\\/schema\\\/person\\\/07f21edce43c3991b015962b083eb122\",\"name\":\"LOE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97cc37bfd932c37d2e1939d44cf9d2225d031ff030e3625cfb873b4481e03ed0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97cc37bfd932c37d2e1939d44cf9d2225d031ff030e3625cfb873b4481e03ed0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97cc37bfd932c37d2e1939d44cf9d2225d031ff030e3625cfb873b4481e03ed0?s=96&d=mm&r=g\",\"caption\":\"LOE\"},\"sameAs\":[\"https:\\\/\\\/www.thermohauser.de\\\/ratgeber\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Um den Globus: Das sind die Lieblings-Office-Lunches &#187; Thermohauser Blog","description":"Italien, Frankreich, Indien und Co.: Diese Lieblings-Office-Lunches sorgen f\u00fcr ein kleines bisschen Urlaubs-Flair im Office! Lassen Sie sich von diesen Leckereien \u00fcberzeugen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/","og_locale":"de_DE","og_type":"article","og_title":"Um den Globus: Das sind die Lieblings-Office-Lunches &#187; Thermohauser Blog","og_description":"Italien, Frankreich, Indien und Co.: Diese Lieblings-Office-Lunches sorgen f\u00fcr ein kleines bisschen Urlaubs-Flair im Office! Lassen Sie sich von diesen Leckereien \u00fcberzeugen.","og_url":"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/","og_site_name":"Thermohauser Blog","article_published_time":"2021-08-11T07:10:14+00:00","article_modified_time":"2021-08-12T09:16:12+00:00","og_image":[{"width":1241,"height":827,"url":"https:\/\/www.thermohauser.de\/blog\/wp-content\/uploads\/2021\/08\/202106_Blogartikel-05_iStock-1132762174_klein.jpg","type":"image\/jpeg"}],"author":"LOE","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"LOE","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/#article","isPartOf":{"@id":"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/"},"author":{"name":"LOE","@id":"https:\/\/www.thermohauser.de\/blog\/#\/schema\/person\/07f21edce43c3991b015962b083eb122"},"headline":"Um den Globus: Das sind die Lieblings-Office-Lunches","datePublished":"2021-08-11T07:10:14+00:00","dateModified":"2021-08-12T09:16:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/"},"wordCount":790,"commentCount":0,"publisher":{"@id":"https:\/\/www.thermohauser.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thermohauser.de\/blog\/wp-content\/uploads\/2021\/08\/202106_Blogartikel-05_iStock-1132762174_klein.jpg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/","url":"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/","name":"Um den Globus: Das sind die Lieblings-Office-Lunches &#187; Thermohauser Blog","isPartOf":{"@id":"https:\/\/www.thermohauser.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/#primaryimage"},"image":{"@id":"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thermohauser.de\/blog\/wp-content\/uploads\/2021\/08\/202106_Blogartikel-05_iStock-1132762174_klein.jpg","datePublished":"2021-08-11T07:10:14+00:00","dateModified":"2021-08-12T09:16:12+00:00","description":"Italien, Frankreich, Indien und Co.: Diese Lieblings-Office-Lunches sorgen f\u00fcr ein kleines bisschen Urlaubs-Flair im Office! Lassen Sie sich von diesen Leckereien \u00fcberzeugen.","breadcrumb":{"@id":"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/#primaryimage","url":"https:\/\/www.thermohauser.de\/blog\/wp-content\/uploads\/2021\/08\/202106_Blogartikel-05_iStock-1132762174_klein.jpg","contentUrl":"https:\/\/www.thermohauser.de\/blog\/wp-content\/uploads\/2021\/08\/202106_Blogartikel-05_iStock-1132762174_klein.jpg","width":1241,"height":827,"caption":"Weltweit gibt es verschiedene Lieblings-Office-Lunches. F\u00fcr ein bisschen Abwechslung sorgt eine \u00dcbersicht einiger B\u00fcro-Klassiker. Wie w\u00e4re es mal mit Pasta mit Thunfisch, Oliven und Tomaten?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thermohauser.de\/blog\/um-den-globus-das-sind-die-lieblings-office-lunches\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.thermohauser.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Allgemein","item":"https:\/\/www.thermohauser.de\/blog\/allgemein\/"},{"@type":"ListItem","position":3,"name":"Um den Globus: Das sind die Lieblings-Office-Lunches"}]},{"@type":"WebSite","@id":"https:\/\/www.thermohauser.de\/blog\/#website","url":"https:\/\/www.thermohauser.de\/blog\/","name":"Thermohauser Blog","description":"","publisher":{"@id":"https:\/\/www.thermohauser.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thermohauser.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.thermohauser.de\/blog\/#organization","name":"thermohauser GmbH","url":"https:\/\/www.thermohauser.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.thermohauser.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.thermohauser.de\/ratgeber\/wp-content\/uploads\/2021\/05\/logo-tablet.png","contentUrl":"https:\/\/www.thermohauser.de\/ratgeber\/wp-content\/uploads\/2021\/05\/logo-tablet.png","width":175,"height":80,"caption":"thermohauser GmbH"},"image":{"@id":"https:\/\/www.thermohauser.de\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.thermohauser.de\/blog\/#\/schema\/person\/07f21edce43c3991b015962b083eb122","name":"LOE","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/97cc37bfd932c37d2e1939d44cf9d2225d031ff030e3625cfb873b4481e03ed0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97cc37bfd932c37d2e1939d44cf9d2225d031ff030e3625cfb873b4481e03ed0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97cc37bfd932c37d2e1939d44cf9d2225d031ff030e3625cfb873b4481e03ed0?s=96&d=mm&r=g","caption":"LOE"},"sameAs":["https:\/\/www.thermohauser.de\/ratgeber"]}]}},"_links":{"self":[{"href":"https:\/\/www.thermohauser.de\/blog\/wp-json\/wp\/v2\/posts\/192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thermohauser.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thermohauser.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thermohauser.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thermohauser.de\/blog\/wp-json\/wp\/v2\/comments?post=192"}],"version-history":[{"count":8,"href":"https:\/\/www.thermohauser.de\/blog\/wp-json\/wp\/v2\/posts\/192\/revisions"}],"predecessor-version":[{"id":213,"href":"https:\/\/www.thermohauser.de\/blog\/wp-json\/wp\/v2\/posts\/192\/revisions\/213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thermohauser.de\/blog\/wp-json\/wp\/v2\/media\/211"}],"wp:attachment":[{"href":"https:\/\/www.thermohauser.de\/blog\/wp-json\/wp\/v2\/media?parent=192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thermohauser.de\/blog\/wp-json\/wp\/v2\/categories?post=192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thermohauser.de\/blog\/wp-json\/wp\/v2\/tags?post=192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}